{"id":62,"date":"2020-06-03T09:25:39","date_gmt":"2020-06-03T09:25:39","guid":{"rendered":"https:\/\/cardioly-demo.pbminfotech.com\/demo1\/?page_id=12842"},"modified":"2023-09-11T10:01:16","modified_gmt":"2023-09-11T15:01:16","slug":"contacto","status":"publish","type":"page","link":"https:\/\/drakatherineromero.surgeryk.com\/en\/contacto\/","title":{"rendered":"Contact"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"62\" class=\"elementor elementor-62\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1683ee1 elementor-section-full_width elementor-section-stretched dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"1683ee1\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-367c472 dsvy-bg-color-over-image\" data-id=\"367c472\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-03709e4 elementor-section-full_width dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"03709e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca8f73f dsvy-bg-color-over-image\" data-id=\"ca8f73f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e3aad4 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6e3aad4\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"587\" height=\"1024\" src=\"https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-587x1024.png\" class=\"attachment-large size-large wp-image-270\" alt=\"\" srcset=\"https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-587x1024.png 587w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-172x300.png 172w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-768x1339.png 768w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-881x1536.png 881w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-1175x2048.png 1175w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-770x1342.png 770w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2.png 1332w\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-debab1c elementor-invisible elementor-widget elementor-widget-image\" data-id=\"debab1c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"587\" height=\"1024\" src=\"https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-587x1024.png\" class=\"attachment-large size-large wp-image-270\" alt=\"\" srcset=\"https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-587x1024.png 587w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-172x300.png 172w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-768x1339.png 768w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-881x1536.png 881w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-1175x2048.png 1175w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2-770x1342.png 770w, https:\/\/drakatherineromero.surgeryk.com\/wp-content\/uploads\/2023\/08\/IMG_3629-2.png 1332w\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2604b10 dsvy-bg-color-yes dsvy-elementor-bg-color-white dsvy-bg-color-over-image\" data-id=\"2604b10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fdd60a elementor-widget elementor-widget-heading\" data-id=\"1fdd60a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact details<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d3543 elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"26d3543\" data-element_type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-local-phone\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tPhone\r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\"><a href=\"tel: 593988138756\">EC: +593 98 813 8756 <\/a>  <br>\n<a href=\"tel: 525541585520\">MX: +52 55 4158 5520 <\/a><\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d3404c elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"5d3404c\" data-element_type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-location-city\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tLocation\r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\">Ecuador <br>\nMexico<\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39229c8 elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"39229c8\" data-element_type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-email\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tE-mail\r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\"><a href=\"mailto:info@drakatherineromero.com\">Dr. Katherine Romero<\/a><\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-347336a dsvy-contact-social-area elementor-widget elementor-widget-text-editor\" data-id=\"347336a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><ul class=\"dsvy-social-links\"><li class=\"dsvy-social-li dsvy-social-facebook\"><a  href=\"https:\/\/www.facebook.com\/bariatrik.ec\" target=\"_blank\"><span><i class=\"dsvy-base-icon-facebook-squared\"><\/i><\/span><\/a><\/li><li class=\"dsvy-social-li dsvy-social-youtube\"><a  href=\"https:\/\/www.youtube.com\/@Dra.KatherineRomero\/featured\" target=\"_blank\"><span><i class=\"dsvy-base-icon-youtube-play\"><\/i><\/span><\/a><\/li><li class=\"dsvy-social-li dsvy-social-instagram\"><a  href=\"https:\/\/www.instagram.com\/dra.katherineromero\/\" target=\"_blank\"><span><i class=\"dsvy-base-icon-instagram\"><\/i><\/span><\/a><\/li><\/ul><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-89cec70 dsvy-bg-color-over-image\" data-id=\"89cec70\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d76d58 elementor-widget elementor-widget-heading\" data-id=\"7d76d58\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact us<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc651d elementor-widget elementor-widget-text-editor\" data-id=\"1fc651d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We will resolve all your questions and concerns.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07703ec elementor-widget elementor-widget-shortcode\" data-id=\"07703ec\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f42-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/62#wpcf7-f42-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/62#wpcf7-f42-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"42\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f42-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"main-form dsvy-form-style-1\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"phone\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-99\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"text-99\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<div class=\"input-group input-button\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"6\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"message\"><\/textarea><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<div class=\"input-group input-button\">\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-block\" type=\"submit\" value=\"SEND\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aa904e elementor-section-stretched dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aa904e\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ae20d4 dsvy-bg-color-over-image\" data-id=\"6ae20d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-639d03f dsvy-align-center elementor-invisible elementor-widget elementor-widget-dsvy_heading\" data-id=\"639d03f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"dsvy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"dsvy-heading-subheading center-align dsvy-reverse-heading-yes\"><h4 class=\"dsvy-element-subtitle\">\r\n\t\t\t\r\n\t\t\t\tubicaci\u00f3n\r\n\t\t\t\r\n\t\t\t<\/h4>\r\n\t\t<h2 class=\"dsvy-element-title\">\r\n\t\t\t\r\n\t\t\t\t\u00bfD\u00f3nde puedes encontrarnos?\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<div class=\"dsvy-heading-desc\">\n  <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1118b26 dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1118b26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff6b26b dsvy-bg-color-over-image elementor-invisible\" data-id=\"ff6b26b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a9221c dsvy-align-center elementor-invisible elementor-widget elementor-widget-dsvy_heading\" data-id=\"3a9221c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"dsvy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"dsvy-heading-subheading center-align dsvy-reverse-heading-yes\"><h2 class=\"dsvy-element-title\">\r\n\t\t\t\r\n\t\t\t\tEcuador\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<div class=\"dsvy-heading-desc\">\n  <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0723be elementor-widget elementor-widget-osm-map-elementor\" data-id=\"b0723be\" data-element_type=\"widget\" data-widget_type=\"osm-map-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"osm-map-b0723be\" \n        class=\"osm-map-container\" \n        data-center=\"-1.7276749829976,-79.310648936416\"><\/div>        <script type=\"text\/javascript\">\n                    <\/script>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33077c7 dsvy-bg-color-over-image elementor-invisible\" data-id=\"33077c7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b0e6e7 dsvy-align-center elementor-invisible elementor-widget elementor-widget-dsvy_heading\" data-id=\"1b0e6e7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"dsvy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"dsvy-heading-subheading center-align dsvy-reverse-heading-yes\"><h2 class=\"dsvy-element-title\">\r\n\t\t\t\r\n\t\t\t\tMexico\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<div class=\"dsvy-heading-desc\">\n  <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b260cb6 elementor-widget elementor-widget-osm-map-elementor\" data-id=\"b260cb6\" data-element_type=\"widget\" data-widget_type=\"osm-map-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"osm-map-b260cb6\" \n        class=\"osm-map-container\" \n        data-center=\"32.525589,-117.0060973\"><\/div>        <script type=\"text\/javascript\">\n                    <\/script>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Datos de Contacto Tel\u00e9fono EC: +593 98 813 8756 MX: +52 55 4158 5520 Ubicaci\u00f3n Ecuador M\u00e9xico Correo electr\u00f3nico Dra. Katherine Romero Cont\u00e1ctanos Resolveremos todas tus dudas e inquietudes. ubicaci\u00f3n \u00bfD\u00f3nde puedes encontrarnos? Ecuador M\u00e9xico<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-62","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/pages\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":51,"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/pages\/62\/revisions"}],"predecessor-version":[{"id":1097,"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/pages\/62\/revisions\/1097"}],"wp:attachment":[{"href":"https:\/\/drakatherineromero.surgeryk.com\/en\/wp-json\/wp\/v2\/media?parent=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}